 {"id":61,"count":11,"description":"","link":"https:\/\/store.utl-china.com\/ar\/product-category\/%d9%82%d8%b7%d8%b9-%d8%ba%d9%8a%d8%a7%d8%b1-%d8%a7%d9%84%d8%b3%d9%8a%d8%a7%d8%b1%d8%a7%d8%aa\/","name":"\u0642\u0637\u0639 \u063a\u064a\u0627\u0631 \u0627\u0644\u0633\u064a\u0627\u0631\u0627\u062a","slug":"%d9%82%d8%b7%d8%b9-%d8%ba%d9%8a%d8%a7%d8%b1-%d8%a7%d9%84%d8%b3%d9%8a%d8%a7%d8%b1%d8%a7%d8%aa","taxonomy":"product_cat","parent":0,"meta":{"order":["0"],"product_count_product_cat":["76"],"display_type":[""],"thumbnail_id":["5206"]},"_links":{"self":[{"href":"https:\/\/store.utl-china.com\/ar\/wp-json\/wp\/v2\/product_cat\/61"}],"collection":[{"href":"https:\/\/store.utl-china.com\/ar\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/store.utl-china.com\/ar\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/store.utl-china.com\/ar\/wp-json\/wp\/v2\/product?product_cat=61"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}